{"id":2890,"date":"2022-12-08T16:59:20","date_gmt":"2022-12-08T16:59:20","guid":{"rendered":"https:\/\/nissantravelguide.com\/ein-wochenende-in-prag\/"},"modified":"2022-12-12T17:59:19","modified_gmt":"2022-12-12T17:59:19","slug":"ein-wochenende-in-prag","status":"publish","type":"page","link":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/","title":{"rendered":"Ein Wochenende in Prag"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-road-trip.php","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ein Wochenende in Prag\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-08T16:59:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-12-12T17:59:19+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ein Wochenende in Prag\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/ein-wochenende-in-prag\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/ein-wochenende-in-prag\\\/#listItem\",\"name\":\"Ein Wochenende in Prag\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/ein-wochenende-in-prag\\\/#listItem\",\"position\":2,\"name\":\"Ein Wochenende in Prag\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/#organization\",\"url\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/https:\\\/\\\/nissantravelguide.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-favicon.png\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/ein-wochenende-in-prag\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/ein-wochenende-in-prag\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/ein-wochenende-in-prag\\\/#webpage\",\"url\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/ein-wochenende-in-prag\\\/\",\"name\":\"Ein Wochenende in Prag\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/ein-wochenende-in-prag\\\/#breadcrumblist\"},\"datePublished\":\"2022-12-08T16:59:20+00:00\",\"dateModified\":\"2022-12-12T17:59:19+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ein Wochenende in Prag","description":"","canonical_url":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/nissantravelguide.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/#listItem","name":"Ein Wochenende in Prag"}},{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/#listItem","position":2,"name":"Ein Wochenende in Prag","previousItem":{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/de\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/nissantravelguide.com\/de\/#organization","url":"https:\/\/nissantravelguide.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/cropped-favicon.png","@id":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/#organizationLogo"},"image":{"@id":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/#webpage","url":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/","name":"Ein Wochenende in Prag","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/nissantravelguide.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/#breadcrumblist"},"datePublished":"2022-12-08T16:59:20+00:00","dateModified":"2022-12-12T17:59:19+00:00"},{"@type":"WebSite","@id":"https:\/\/nissantravelguide.com\/de\/#website","url":"https:\/\/nissantravelguide.com\/de\/","inLanguage":"de-DE","publisher":{"@id":"https:\/\/nissantravelguide.com\/de\/#organization"}}]},"og:locale":"de_DE","og:type":"article","og:title":"Ein Wochenende in Prag","og:url":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/","og:image":"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png","og:image:secure_url":"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png","article:published_time":"2022-12-08T16:59:20+00:00","article:modified_time":"2022-12-12T17:59:19+00:00","twitter:card":"summary_large_image","twitter:title":"Ein Wochenende in Prag","twitter:image":"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png"},"aioseo_meta_data":{"post_id":"2890","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-12-08 16:59:21","updated":"2025-06-14 06:41:47","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nissantravelguide.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEin Wochenende in Prag\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nissantravelguide.com\/de\/"},{"label":"Ein Wochenende in Prag","link":"https:\/\/nissantravelguide.com\/de\/ein-wochenende-in-prag\/"}],"_links":{"self":[{"href":"https:\/\/nissantravelguide.com\/de\/wp-json\/wp\/v2\/pages\/2890"}],"collection":[{"href":"https:\/\/nissantravelguide.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nissantravelguide.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nissantravelguide.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nissantravelguide.com\/de\/wp-json\/wp\/v2\/comments?post=2890"}],"version-history":[{"count":1,"href":"https:\/\/nissantravelguide.com\/de\/wp-json\/wp\/v2\/pages\/2890\/revisions"}],"predecessor-version":[{"id":4131,"href":"https:\/\/nissantravelguide.com\/de\/wp-json\/wp\/v2\/pages\/2890\/revisions\/4131"}],"wp:attachment":[{"href":"https:\/\/nissantravelguide.com\/de\/wp-json\/wp\/v2\/media?parent=2890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}