{"id":1914,"date":"2022-11-03T10:13:23","date_gmt":"2022-11-03T10:13:23","guid":{"rendered":"https:\/\/nissantravelguide.com\/?page_id=1914"},"modified":"2022-11-28T10:41:08","modified_gmt":"2022-11-28T10:41:08","slug":"hauptpl-31","status":"publish","type":"page","link":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/","title":{"rendered":"Hauptpl. 31"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":1680,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-location.php","meta":{"_acf_changed":false,"footnotes":""},"acf":{"address":"Type 2 11kW: Hauptpl. 31, 2421 Kittsee, Austria","location_type":"charging","map_link":"https:\/\/www.google.co.uk\/maps\/place\/Electric+Vehicle+Charging+Station\/@48.090213,17.0646603,17z\/data=!3m1!4b1!4m5!3m4!1s0x476c89fea041431b:0x8dee879240a7889b!8m2!3d48.090213!4d17.0668543","trip_advisor":"","coordinates":{"latitude":"48.090213","longitude":"17.0646603"},"charging_stations":null},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hauptpl. 31\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-11-03T10:13:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-11-28T10:41:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hauptpl. 31\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/hauptpl-31\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/#listItem\",\"name\":\"Bratislava\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/#listItem\",\"position\":2,\"name\":\"Bratislava\",\"item\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/hauptpl-31\\\/#listItem\",\"name\":\"Hauptpl. 31\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/hauptpl-31\\\/#listItem\",\"position\":3,\"name\":\"Hauptpl. 31\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/#listItem\",\"name\":\"Bratislava\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/#organization\",\"url\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/https:\\\/\\\/nissantravelguide.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-favicon.png\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/hauptpl-31\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/hauptpl-31\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/hauptpl-31\\\/#webpage\",\"url\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/hauptpl-31\\\/\",\"name\":\"Hauptpl. 31\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/bratislava\\\/hauptpl-31\\\/#breadcrumblist\"},\"datePublished\":\"2022-11-03T10:13:23+00:00\",\"dateModified\":\"2022-11-28T10:41:08+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/nissantravelguide.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Hauptpl. 31","description":"","canonical_url":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/nissantravelguide.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/#listItem","name":"Bratislava"}},{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/#listItem","position":2,"name":"Bratislava","item":"https:\/\/nissantravelguide.com\/en\/bratislava\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/#listItem","name":"Hauptpl. 31"},"previousItem":{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/#listItem","position":3,"name":"Hauptpl. 31","previousItem":{"@type":"ListItem","@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/#listItem","name":"Bratislava"}}]},{"@type":"Organization","@id":"https:\/\/nissantravelguide.com\/en\/#organization","url":"https:\/\/nissantravelguide.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/cropped-favicon.png","@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/#organizationLogo"},"image":{"@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/#webpage","url":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/","name":"Hauptpl. 31","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/nissantravelguide.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/#breadcrumblist"},"datePublished":"2022-11-03T10:13:23+00:00","dateModified":"2022-11-28T10:41:08+00:00"},{"@type":"WebSite","@id":"https:\/\/nissantravelguide.com\/en\/#website","url":"https:\/\/nissantravelguide.com\/en\/","inLanguage":"en-US","publisher":{"@id":"https:\/\/nissantravelguide.com\/en\/#organization"}}]},"og:locale":"en_US","og:type":"article","og:title":"Hauptpl. 31","og:url":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/","og:image":"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png","og:image:secure_url":"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png","article:published_time":"2022-11-03T10:13:23+00:00","article:modified_time":"2022-11-28T10:41:08+00:00","twitter:card":"summary_large_image","twitter:title":"Hauptpl. 31","twitter:image":"https:\/\/https:\/\/nissantravelguide.com\/wp-content\/uploads\/2022\/06\/Share.png"},"aioseo_meta_data":{"post_id":"1914","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-11-03 10:13:23","updated":"2025-06-14 06:06:42","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nissantravelguide.com\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nissantravelguide.com\/en\/bratislava\/\" title=\"Bratislava\">Bratislava<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHauptpl. 31\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nissantravelguide.com\/en\/"},{"label":"Bratislava","link":"https:\/\/nissantravelguide.com\/en\/bratislava\/"},{"label":"Hauptpl. 31","link":"https:\/\/nissantravelguide.com\/en\/bratislava\/hauptpl-31\/"}],"_links":{"self":[{"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/pages\/1914"}],"collection":[{"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/comments?post=1914"}],"version-history":[{"count":4,"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/pages\/1914\/revisions"}],"predecessor-version":[{"id":2195,"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/pages\/1914\/revisions\/2195"}],"up":[{"embeddable":true,"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/pages\/1680"}],"wp:attachment":[{"href":"https:\/\/nissantravelguide.com\/en\/wp-json\/wp\/v2\/media?parent=1914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}